{"id":872,"count":1,"description":"","link":"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/","name":"medicijnen","slug":"medicijnen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>medicijnen Archives - Eyes on Animals<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"medicijnen Archives - Eyes on Animals\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Eyes on Animals\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/tag\\\/medicijnen\\\/\",\"url\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/tag\\\/medicijnen\\\/\",\"name\":\"medicijnen Archives - Eyes on Animals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/tag\\\/medicijnen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/tag\\\/medicijnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"medicijnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/\",\"name\":\"Eyes on Animals\",\"description\":\"Watching out for their Welfare\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/#organization\",\"name\":\"Eyes on Animals\",\"url\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eyesonanimals.com\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/logo-450x109.png\",\"contentUrl\":\"https:\\\/\\\/www.eyesonanimals.com\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/logo-450x109.png\",\"width\":450,\"height\":109,\"caption\":\"Eyes on Animals\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eyesonanimals.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.youtube.com\\\/user\\\/EyesonAnimalsinspect?feature=mhee\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"medicijnen Archives - Eyes on Animals","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"medicijnen Archives - Eyes on Animals","og_url":"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/","og_site_name":"Eyes on Animals","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/","url":"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/","name":"medicijnen Archives - Eyes on Animals","isPartOf":{"@id":"https:\/\/www.eyesonanimals.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eyesonanimals.com\/nl\/tag\/medicijnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eyesonanimals.com\/nl\/"},{"@type":"ListItem","position":2,"name":"medicijnen"}]},{"@type":"WebSite","@id":"https:\/\/www.eyesonanimals.com\/nl\/#website","url":"https:\/\/www.eyesonanimals.com\/nl\/","name":"Eyes on Animals","description":"Watching out for their Welfare","publisher":{"@id":"https:\/\/www.eyesonanimals.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eyesonanimals.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.eyesonanimals.com\/nl\/#organization","name":"Eyes on Animals","url":"https:\/\/www.eyesonanimals.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.eyesonanimals.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.eyesonanimals.com\/wp-content\/uploads\/2011\/06\/logo-450x109.png","contentUrl":"https:\/\/www.eyesonanimals.com\/wp-content\/uploads\/2011\/06\/logo-450x109.png","width":450,"height":109,"caption":"Eyes on Animals"},"image":{"@id":"https:\/\/www.eyesonanimals.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.youtube.com\/user\/EyesonAnimalsinspect?feature=mhee"]}]}},"_links":{"self":[{"href":"https:\/\/www.eyesonanimals.com\/nl\/wp-json\/wp\/v2\/tags\/872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eyesonanimals.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.eyesonanimals.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.eyesonanimals.com\/nl\/wp-json\/wp\/v2\/posts?tags=872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}